{"id":18,"date":"2015-08-08T00:49:25","date_gmt":"2015-08-08T00:49:25","guid":{"rendered":"http:\/\/redesow.faccat.br\/wordpress\/sapiranga\/?p=18"},"modified":"2015-08-08T00:50:27","modified_gmt":"2015-08-08T00:50:27","slug":"o-homem-jato","status":"publish","type":"post","link":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/o-homem-jato\/","title":{"rendered":"O Homem Jato"},"content":{"rendered":"<p>O V\u00eddeo conta a hist\u00f3ria de um homem chamado Yves Rossy\u00a0que desde crian\u00e7a sonhava em voar, em desafiar a gravidade e ficou conhecido como \u00a0homem jato.<\/p>\n<p>Yves \u00e9 Piloto, engenheiro, inventor e entusiasta da avia\u00e7\u00e3o, ele foi a primeira pessoa a conseguir sustentar o voo humano usando apenas uma asa<b>.<\/b><\/p>\n<p>Ele conta que consegue guiar o trajeto com o movimento do corpo, o equipamento (asas) segue os movimentos do usu\u00e1rio.<\/p>\n<p>Com o equipamento, ele consegue chegar a uma velocidade de mais de 300 km\/h e em torno de 3,5 mil metros de altura, sendo que o voo tem dura\u00e7\u00e3o de 8 \u00e0 15 minutos.<\/p>\n<p>O v\u00eddeo sobre o Homem jato pode ser utilizado de forma interdisciplinar nas aulas de geografia, artes, f\u00edsica, matem\u00e1tica e em outras tantas disciplinas. Em geografia pela quest\u00e3o visual (relevo), em artes pelas tantas paisagens e imagens presentes no v\u00eddeo, em matem\u00e1tica\/f\u00edsica para calcular a velocidade m\u00e9dia, dist\u00e2ncia, tempo, altitude, entre outros.<\/p>\n<p>&nbsp;<\/p>\n<p>Su\u00e9len Guterres e S\u00e9rgio Fernandes<\/p>\n<figure id=\"attachment_19\" class=\"thumbnail wp-caption alignnone\" style=\"width: 300px\"><a href=\"http:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19\" src=\"http:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato-300x221.jpg\" alt=\"SONY DSC\" width=\"300\" height=\"221\" srcset=\"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato-300x221.jpg 300w, https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato.jpg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"caption wp-caption-text\">Homem Jato<\/figcaption><\/figure>\n<p><a href=\"http:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-21\" src=\"http:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato1-300x158.jpg\" alt=\"jato1\" width=\"300\" height=\"158\" srcset=\"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato1-300x158.jpg 300w, https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato1-1024x538.jpg 1024w, https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-content\/uploads\/sites\/21\/jato1.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O V\u00eddeo conta a hist\u00f3ria de um homem chamado Yves Rossy\u00a0que desde crian\u00e7a sonhava em voar, em desafiar a gravidade e ficou conhecido como \u00a0homem jato. Yves \u00e9 Piloto, engenheiro, inventor e entusiasta da avia\u00e7\u00e3o, ele foi a primeira pessoa a conseguir sustentar o voo humano usando apenas uma asa. Ele conta que consegue guiar o trajeto com o movimento do corpo, o equipamento (asas) segue os movimentos do usu\u00e1rio. Com o equipamento, ele consegue chegar a uma velocidade de mais de 300 km\/h e em torno de 3,5 mil metros de altura, sendo que o voo tem dura\u00e7\u00e3o de 8 \u00e0 15 minutos. O v\u00eddeo sobre o Homem jato pode ser utilizado de forma interdisciplinar nas aulas de geografia, artes, f\u00edsica, matem\u00e1tica e em outras tantas disciplinas. Em geografia pela quest\u00e3o visual (relevo), em artes pelas tantas paisagens e &hellip; <a href=\"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/o-homem-jato\/\">Continua<\/a><\/p>\n","protected":false},"author":181,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/posts\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/users\/181"}],"replies":[{"embeddable":true,"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":2,"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/posts\/18\/revisions"}],"predecessor-version":[{"id":29,"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/posts\/18\/revisions\/29"}],"wp:attachment":[{"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/media?parent=18"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/categories?post=18"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redesow.faccat.br\/wordpress\/sapiranga\/wp-json\/wp\/v2\/tags?post=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}